{"id":35617,"date":"2026-04-01T10:47:54","date_gmt":"2026-04-01T08:47:54","guid":{"rendered":"https:\/\/webnemji.azurewebsites.net\/?p=35617"},"modified":"2026-04-01T11:43:03","modified_gmt":"2026-04-01T09:43:03","slug":"porodnice-dvere","status":"publish","type":"post","link":"https:\/\/webnemji.azurewebsites.net\/en\/porodnice-dvere\/","title":{"rendered":"Porodnice v Jihlav\u011b otev\u0159e sv\u00e9 dve\u0159e: p\u0159ij\u010fte nahl\u00e9dnout tam, kde se rod\u00ed nov\u00e9 \u017eivoty"},"content":{"rendered":"<div id=\"cmsmasters_row_\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div id=\"cmsmasters_column_\" class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_column_inner\"><div class=\"cmsmasters_text\">\n<p style=\"text-align: left;\"><nav aria-label=\"breadcrumbs\">\n            <div class=\"breadcrumb-container theme1\">\n                <ol>\n                                    <\/ol>\n            <\/div>\n        <\/nav>    <script type=\"application\/ld+json\">\n        {\n            \"@context\": \"http:\/\/schema.org\",\n            \"@type\": \"BreadcrumbList\",\n            \"itemListElement\": [\n                            ]\n        }\n    <\/script>\n   \n    <script>\n            <\/script>\n<\/p>\n<\/div>\n<div id=\"cmsmasters_divider_1sk6yyldai\" class=\"cmsmasters_divider cmsmasters_divider_width_short cmsmasters_divider_pos_center\"><\/div>\n<div class=\"cmsmasters_text news-content-anot\">\n<p>Nemocnice Jihlava srde\u010dn\u011b zve nejenom budouc\u00ed maminky na Den otev\u0159en\u00fdch dve\u0159\u00ed porodnice, kter\u00fd se uskute\u010dn\u00ed <strong>15. dubna od 14:00<\/strong> ve velk\u00e9 zasedac\u00ed m\u00edstnosti nemocnice. N\u00e1v\u0161t\u011bvn\u00edci se dozv\u00ed v\u00edce o p\u00e9\u010di o maminky a novorozence a budou m\u00edt tak\u00e9 mo\u017enost nahl\u00e9dnout do prost\u0159ed\u00ed porodn\u00edch s\u00e1l\u016f.<\/p>\n<\/div>\n<div class=\"cmsmasters_text news-content\">\n<p>C\u00edlem akce je p\u0159edstavit z\u00e1jemc\u016fm, jak prob\u00edh\u00e1 p\u00e9\u010de o \u017eeny v pr\u016fb\u011bhu t\u011bhotenstv\u00ed, porodu i po n\u011bm, a z\u00e1rove\u0148 d\u00e1t prostor pro ot\u00e1zky a osobn\u00ed setk\u00e1n\u00ed se zdravotnick\u00fdm person\u00e1lem porodnice.<\/p>\n<p>Sou\u010d\u00e1st\u00ed programu budou odborn\u00e9 p\u0159edn\u00e1\u0161ky l\u00e9ka\u0159\u016f a porodn\u00edch asistentek, kte\u0159\u00ed p\u0159ibl\u00ed\u017e\u00ed jednotliv\u00e9 f\u00e1ze p\u00e9\u010de o maminku a d\u00edt\u011b.<\/p>\n<p><strong>Program:<\/strong><\/p>\n<ul>\n<li>Zah\u00e1jen\u00ed \u2013 prim. MUDr. Petra Herboltov\u00e1<\/li>\n<li>P\u00e9\u010de o \u017eenu v t\u011bhotenstv\u00ed a za porodu z pohledu l\u00e9ka\u0159e \u2013 MUDr. Kate\u0159ina Dvo\u0159\u00e1kov\u00e1<\/li>\n<li>P\u00e9\u010de o \u017eenu v pr\u016fb\u011bhu porodu \u2013 Bc. Romana Da\u0148helov\u00e1<\/li>\n<li>P\u00e9\u010de o novorozence po porodu \u2013 Bc. Kate\u0159ina Bl\u00e1hov\u00e1<\/li>\n<li>\u0160estined\u011bl\u00ed \u2013 Bc. Marie Mejst\u0159\u00edkov\u00e1<\/li>\n<\/ul>\n<p>Po skon\u010den\u00ed p\u0159edn\u00e1\u0161ek bude n\u00e1sledovat prohl\u00eddka porodn\u00edch s\u00e1l\u016f, pokud to aktu\u00e1ln\u00ed provozn\u00ed situace umo\u017en\u00ed.<\/p>\n<p>\u00da\u010dast na akci je zdarma, z kapacitn\u00edch d\u016fvod\u016f je v\u0161ak nutn\u00e9 se p\u0159edem registrovat prost\u0159ednictv\u00edm rezerva\u010dn\u00edho syst\u00e9mu Reenio.<\/p>\n<p>Nemocnice Jihlava dlouhodob\u011b usiluje o to, aby budouc\u00edm rodi\u010d\u016fm poskytla nejen kvalitn\u00ed zdravotn\u00ed p\u00e9\u010di, ale tak\u00e9 dostatek informac\u00ed a jistoty p\u0159ed jedn\u00edm z nejd\u016fle\u017eit\u011bj\u0161\u00edch \u017eivotn\u00edch okam\u017eik\u016f.<\/p>\n<p>&nbsp;<\/p>\n<p><b><span class=\"fontColorThemeDarkAlt\" style=\"color: #003c56;\">Nemocnice Jihlava<\/span>\u00a0<\/b><b>|<\/b><b>\u00a0<\/b><span class=\"fontColorThemePrimary\" style=\"color: #bf311f;\"><b>Va\u0161e nemocnice<\/b><\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"\/wp-content\/uploads\/2026\/04\/DEN_OTEVERENYCH_DVERI_NEMJI-1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-35619\" src=\"\/wp-content\/uploads\/2026\/04\/DEN_OTEVERENYCH_DVERI_NEMJI-1-scaled.jpg\" alt=\"let\u00e1k - den otev\u0159en\u00fdch dve\u0159\u00ed porodnice\" width=\"400\" height=\"565\" srcset=\"\/wp-content\/uploads\/2026\/04\/DEN_OTEVERENYCH_DVERI_NEMJI-1-scaled.jpg 1813w, \/wp-content\/uploads\/2026\/04\/DEN_OTEVERENYCH_DVERI_NEMJI-1-212x300.jpg 212w, \/wp-content\/uploads\/2026\/04\/DEN_OTEVERENYCH_DVERI_NEMJI-1-725x1024.jpg 725w, \/wp-content\/uploads\/2026\/04\/DEN_OTEVERENYCH_DVERI_NEMJI-1-768x1085.jpg 768w, \/wp-content\/uploads\/2026\/04\/DEN_OTEVERENYCH_DVERI_NEMJI-1-1088x1536.jpg 1088w, \/wp-content\/uploads\/2026\/04\/DEN_OTEVERENYCH_DVERI_NEMJI-1-1450x2048.jpg 1450w, \/wp-content\/uploads\/2026\/04\/DEN_OTEVERENYCH_DVERI_NEMJI-1-8x12.jpg 8w, \/wp-content\/uploads\/2026\/04\/DEN_OTEVERENYCH_DVERI_NEMJI-1-580x819.jpg 580w, \/wp-content\/uploads\/2026\/04\/DEN_OTEVERENYCH_DVERI_NEMJI-1-860x1215.jpg 860w, \/wp-content\/uploads\/2026\/04\/DEN_OTEVERENYCH_DVERI_NEMJI-1-1160x1638.jpg 1160w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<div class=\"cmsmasters_text\">\n<p>&nbsp;<\/p>\n<\/div>\n<div id=\"cmsmasters_divider_s8rl0slo4r\" class=\"cmsmasters_divider cmsmasters_divider_width_long cmsmasters_divider_pos_center\"><\/div>\n<div id=\"cmsmasters_button_m9j7eykyp\" class=\"button_wrap\"><a href=\"\/aktuality\/\" class=\"cmsmasters_button all-news-btn\"><span>V\u0161echny aktuality\u00a0\u00a0\u271a<\/span><\/a><\/div>\n<div class=\"cmsmasters_sidebar sidebar_layout_11 post-custom-sidebar\"><aside id=\"block-12\" class=\"widget widget_block\"><div class='pt-cv-wrapper'> <h3 class=\"pt-cv-heading-container heading1\" data-blockid=\"fysa6n9v\"><span class=\"pt-cv-heading\"> Posledn\u00ed aktuality <\/span><\/h3><div class=\"pt-cv-view pt-cv-blockgrid iscvblock iscvreal grid1 layout1\" id=\"pt-cv-view-fysa6n9v\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"5\"><div class=\" pt-cv-content-item pt-cv-1-col\" ><div class=\"pt-cv-thumb-wrapper  \"><a href=\"https:\/\/webnemji.azurewebsites.net\/en\/stare-leky-muzete-nove-odevzdat-kdykoliv-nemocnice-jihlava-ma-pred-lekarnou-sberny-box\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"400\" src=\"\/wp-content\/uploads\/2026\/07\/BOX2-580x400.png\" class=\"pt-cv-thumbnail\" alt=\"box l\u00e9k\u00e1rna\" \/><\/a><\/div>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/webnemji.azurewebsites.net\/en\/stare-leky-muzete-nove-odevzdat-kdykoliv-nemocnice-jihlava-ma-pred-lekarnou-sberny-box\/\" class=\"_self\" target=\"_self\" >Star\u00e9 l\u00e9ky m\u016f\u017eete nov\u011b odevzdat kdykoliv. Nemocnice Jihlava m\u00e1 p\u0159ed l\u00e9k\u00e1rnou sb\u011brn\u00fd box<\/a><\/h5>\n<div class=\"pt-cv-content\">Box je um\u00edst\u011bn p\u0159ed vstupem do nemocni\u010dn\u00ed l\u00e9k\u00e1rny ...<\/div>\n<div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/webnemji.azurewebsites.net\/en\/stare-leky-muzete-nove-odevzdat-kdykoliv-nemocnice-jihlava-ma-pred-lekarnou-sberny-box\/\" class=\"_self pt-cv-readmore btn btn-success\" target=\"_self\" >P\u0159e\u010d\u00edst\u00a0\u00a0\u271a<\/a><\/div><\/div>\n<div class=\" pt-cv-content-item pt-cv-1-col\" ><div class=\"pt-cv-thumb-wrapper  \"><a href=\"https:\/\/webnemji.azurewebsites.net\/en\/jihlavska-zachytka-zazila-rekordni-cerven\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"400\" src=\"\/wp-content\/uploads\/2026\/07\/PZS1-580x400.jpg\" class=\"pt-cv-thumbnail\" alt=\"PZS\" \/><\/a><\/div>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/webnemji.azurewebsites.net\/en\/jihlavska-zachytka-zazila-rekordni-cerven\/\" class=\"_self\" target=\"_self\" >Jihlavsk\u00e1 z\u00e1chytka za\u017eila rekordn\u00ed \u010derven<\/a><\/h5>\n<div class=\"pt-cv-content\">Rekordn\u00edch 153 p\u0159ijat\u00fdch osob b\u011bhem jedin\u00e9ho m\u011bs\u00edce ...<\/div>\n<div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/webnemji.azurewebsites.net\/en\/jihlavska-zachytka-zazila-rekordni-cerven\/\" class=\"_self pt-cv-readmore btn btn-success\" target=\"_self\" >P\u0159e\u010d\u00edst\u00a0\u00a0\u271a<\/a><\/div><\/div>\n<div class=\" pt-cv-content-item pt-cv-1-col\" ><div class=\"pt-cv-thumb-wrapper  \"><a href=\"https:\/\/webnemji.azurewebsites.net\/en\/terminy-letni-dovolene-na-nasem-odberovem-stredisku\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"400\" src=\"\/wp-content\/uploads\/2024\/04\/kapka_dovo_clean-580x400.jpg\" class=\"pt-cv-thumbnail\" alt=\"kapka krve na dovolen\u00e9\" \/><\/a><\/div>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/webnemji.azurewebsites.net\/en\/terminy-letni-dovolene-na-nasem-odberovem-stredisku\/\" class=\"_self\" target=\"_self\" >Term\u00edny letn\u00ed dovolen\u00e9 na na\u0161em odb\u011brov\u00e9m st\u0159edisku.<\/a><\/h5>\n<div class=\"pt-cv-content\">Uzav\u0159en\u00ed na\u0161eho odb\u011brov\u00e9ho st\u0159ediska o letn\u00edch pr\u00e1zdnin\u00e1ch ...<\/div>\n<div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/webnemji.azurewebsites.net\/en\/terminy-letni-dovolene-na-nasem-odberovem-stredisku\/\" class=\"_self pt-cv-readmore btn btn-success\" target=\"_self\" >P\u0159e\u010d\u00edst\u00a0\u00a0\u271a<\/a><\/div><\/div>\n<div class=\" pt-cv-content-item pt-cv-1-col\" ><div class=\"pt-cv-thumb-wrapper  \"><a href=\"https:\/\/webnemji.azurewebsites.net\/en\/prvni-na-vysocine-jihlavska-porodnice-ziskala-oceneni-za-peci-o-dusevni-zdravi-rodicek\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"400\" src=\"\/wp-content\/uploads\/2026\/06\/Screening-DZ-certifikat-580x400.png\" class=\"pt-cv-thumbnail\" alt=\"ocen\u011bn\u00ed porordnice\" \/><\/a><\/div>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/webnemji.azurewebsites.net\/en\/prvni-na-vysocine-jihlavska-porodnice-ziskala-oceneni-za-peci-o-dusevni-zdravi-rodicek\/\" class=\"_self\" target=\"_self\" >Prvn\u00ed na Vyso\u010din\u011b: jihlavsk\u00e1 porodnice z\u00edskala ocen\u011bn\u00ed za p\u00e9\u010di o du\u0161evn\u00ed zdrav\u00ed rodi\u010dek<\/a><\/h5>\n<div class=\"pt-cv-content\">Porodnice Nemocnice Jihlava jako prvn\u00ed na Vyso\u010din\u011b z\u00edskala ocen\u011bn\u00ed Centra ...<\/div>\n<div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/webnemji.azurewebsites.net\/en\/prvni-na-vysocine-jihlavska-porodnice-ziskala-oceneni-za-peci-o-dusevni-zdravi-rodicek\/\" class=\"_self pt-cv-readmore btn btn-success\" target=\"_self\" >P\u0159e\u010d\u00edst\u00a0\u00a0\u271a<\/a><\/div><\/div>\n<div class=\" pt-cv-content-item pt-cv-1-col\" ><div class=\"pt-cv-thumb-wrapper  \"><a href=\"https:\/\/webnemji.azurewebsites.net\/en\/nemocnice-jihlava-rozsiruje-parkovaci-system-o-dalsi-parkoviste\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"400\" src=\"\/wp-content\/uploads\/2026\/06\/IMG_8698-580x400.jpeg\" class=\"pt-cv-thumbnail\" alt=\"nov\u00e9 parkovi\u0161t\u011b\" \/><\/a><\/div>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/webnemji.azurewebsites.net\/en\/nemocnice-jihlava-rozsiruje-parkovaci-system-o-dalsi-parkoviste\/\" class=\"_self\" target=\"_self\" >Nemocnice Jihlava roz\u0161i\u0159uje parkovac\u00ed syst\u00e9m o dal\u0161\u00ed parkovi\u0161t\u011b<\/a><\/h5>\n<div class=\"pt-cv-content\">Nemocnice roz\u0161\u00ed\u0159ila sv\u016fj parkovac\u00ed syst\u00e9m o dal\u0161\u00ed parkovi\u0161t\u011b v are\u00e1lu ...<\/div>\n<div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/webnemji.azurewebsites.net\/en\/nemocnice-jihlava-rozsiruje-parkovaci-system-o-dalsi-parkoviste\/\" class=\"_self pt-cv-readmore btn btn-success\" target=\"_self\" >P\u0159e\u010d\u00edst\u00a0\u00a0\u271a<\/a><\/div><\/div><\/div><\/div> <\/div> <style>\n\n#pt-cv-view-fysa6n9v .pt-cv-content-item { border-style: none;border-radius: 0px 0px 0px 0px; }#pt-cv-view-fysa6n9v .pt-cv-meta-fields {  }#pt-cv-view-fysa6n9v .pt-cv-meta-fields * { font-size: 13px; }.pt-cv-heading-container[data-blockid=\"fysa6n9v\"] {  }.pt-cv-heading-container[data-blockid=\"fysa6n9v\"] * { color: #003c56;font-weight: 600;font-size: 16px; }#pt-cv-view-fysa6n9v .pt-cv-thumb-wrapper {  }#pt-cv-view-fysa6n9v[class*=\"cveffect\"] .pt-cv-thumb-wrapper, #pt-cv-view-fysa6n9v:not([class*=\"cveffect\"]) .pt-cv-thumbnail { border-radius: 20px 20px 20px 20px; }#pt-cv-view-fysa6n9v .pt-cv-thumbnail {  }#pt-cv-view-fysa6n9v .pt-cv-title a { display: block;color: #003c56; }#pt-cv-view-fysa6n9v .pt-cv-title:not(.pt-cv-titlesm) a { font-weight: 600;text-decoration: none;font-size: 15px; }#pt-cv-view-fysa6n9v .pt-cv-titlesm a { font-weight: 600;font-size: 18px; }#pt-cv-view-fysa6n9v .pt-cv-content { font-size: 14px; }#pt-cv-view-fysa6n9v .pt-cv-rmwrap {  }#pt-cv-view-fysa6n9v .pt-cv-readmore { color: #4f5a61;background-color: #edf0f2;font-size: 14px;border-radius: 10px 10px 10px 10px; }#pt-cv-view-fysa6n9v .pt-cv-taxoterm {  }#pt-cv-view-fysa6n9v .pt-cv-taxoterm * { color: #222;background-color: #fff6f6;font-size: 14px; }#pt-cv-view-fysa6n9v + .pt-cv-pagination-wrapper {  }#pt-cv-view-fysa6n9v + .pt-cv-pagination-wrapper a { font-size: 14px; }#pt-cv-view-fysa6n9v > .pt-cv-page {grid-template-columns: repeat(5, 1fr);grid-gap: 20px;}#pt-cv-view-fysa6n9v .pt-cv-title a:hover { color: #bf311f; }#pt-cv-view-fysa6n9v .pt-cv-title:not(.pt-cv-titlesm) a:hover {  }#pt-cv-view-fysa6n9v .pt-cv-rmwrap:hover {  }#pt-cv-view-fysa6n9v .pt-cv-readmore:hover { color: #ffffff;background-color: #bf311f; }\n@media all and (max-width: 1024px) { \n#pt-cv-view-fysa6n9v > .pt-cv-page {grid-template-columns: repeat(3, 1fr);grid-gap: 15px;}\n} \n@media all and (max-width: 767px) { \n#pt-cv-view-fysa6n9v > .pt-cv-page {grid-template-columns: repeat(1, 1fr);grid-gap: 10px;}\n} <\/style><\/aside><div class=\"cl\"><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Den otev\u0159en\u00fdch dve\u0159\u00ed porodnice, kter\u00fd se uskute\u010dn\u00ed 15. dubna od 14:00 ve velk\u00e9 zasedac\u00ed m\u00edstnosti nemocnice<\/p>","protected":false},"author":5,"featured_media":35619,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":"","_members_access_role":[],"_members_access_error":"","_links_to":"","_links_to_target":""},"categories":[49],"tags":[],"class_list":["post-35617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuality"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 06:01:26","action":"change-status","newStatus":"trash","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/webnemji.azurewebsites.net\/en\/wp-json\/wp\/v2\/posts\/35617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webnemji.azurewebsites.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webnemji.azurewebsites.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webnemji.azurewebsites.net\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/webnemji.azurewebsites.net\/en\/wp-json\/wp\/v2\/comments?post=35617"}],"version-history":[{"count":0,"href":"https:\/\/webnemji.azurewebsites.net\/en\/wp-json\/wp\/v2\/posts\/35617\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/webnemji.azurewebsites.net\/en\/wp-json\/wp\/v2\/media\/35619"}],"wp:attachment":[{"href":"https:\/\/webnemji.azurewebsites.net\/en\/wp-json\/wp\/v2\/media?parent=35617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webnemji.azurewebsites.net\/en\/wp-json\/wp\/v2\/categories?post=35617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webnemji.azurewebsites.net\/en\/wp-json\/wp\/v2\/tags?post=35617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}