{"id":17961,"date":"2023-09-05T10:38:23","date_gmt":"2023-09-05T08:38:23","guid":{"rendered":"https:\/\/nemji.rs-kovarik.cz\/?post_type=project&#038;p=17961"},"modified":"2024-01-29T10:43:17","modified_gmt":"2024-01-29T09:43:17","slug":"aro","status":"publish","type":"project","link":"https:\/\/webnemji.azurewebsites.net\/en\/project\/aro\/","title":{"rendered":"ARU"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><i class=\"fa-solid fa-compass\"><\/i>&nbsp;&nbsp;Block B, ground floor \u2013 1st floor<br \/>\n<i class=\"fa-solid fa-phone\"><\/i>&nbsp;&nbsp;+420 567 157 389<\/p>","protected":false},"author":1,"featured_media":28744,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":"","_members_access_role":[],"_members_access_error":"","_links_to":"","_links_to_target":""},"pj-categs":[113,283,282],"pj-tags":[],"class_list":["post-17961","project","type-project","status-publish","format-standard","has-post-thumbnail","hentry","pj-categs-ambulance","pj-categs-jip","pj-categs-luzka"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 06:03:05","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"pj-categs","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/webnemji.azurewebsites.net\/en\/wp-json\/wp\/v2\/project\/17961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webnemji.azurewebsites.net\/en\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/webnemji.azurewebsites.net\/en\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/webnemji.azurewebsites.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webnemji.azurewebsites.net\/en\/wp-json\/wp\/v2\/comments?post=17961"}],"version-history":[{"count":0,"href":"https:\/\/webnemji.azurewebsites.net\/en\/wp-json\/wp\/v2\/project\/17961\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/webnemji.azurewebsites.net\/en\/wp-json\/wp\/v2\/media\/28744"}],"wp:attachment":[{"href":"https:\/\/webnemji.azurewebsites.net\/en\/wp-json\/wp\/v2\/media?parent=17961"}],"wp:term":[{"taxonomy":"pj-categs","embeddable":true,"href":"https:\/\/webnemji.azurewebsites.net\/en\/wp-json\/wp\/v2\/pj-categs?post=17961"},{"taxonomy":"pj-tags","embeddable":true,"href":"https:\/\/webnemji.azurewebsites.net\/en\/wp-json\/wp\/v2\/pj-tags?post=17961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}